{"id":137,"date":"2025-08-21T17:20:53","date_gmt":"2025-08-21T09:20:53","guid":{"rendered":"https:\/\/yongqingbeadsfactory.com\/?p=137"},"modified":"2025-08-21T17:21:20","modified_gmt":"2025-08-21T09:21:20","slug":"double-coated-glass-microspheres","status":"publish","type":"post","link":"https:\/\/yongqingbeadsfactory.com\/pt\/2025\/08\/21\/double-coated-glass-microspheres\/","title":{"rendered":"Microesferas de vidro com revestimento duplo"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/yongqingbeadsfactory.com\/wp-content\/uploads\/2025\/08\/05.jpg\" alt=\"\" class=\"wp-image-138\" srcset=\"https:\/\/yongqingbeadsfactory.com\/wp-content\/uploads\/2025\/08\/05.jpg 600w, https:\/\/yongqingbeadsfactory.com\/wp-content\/uploads\/2025\/08\/05-300x300.jpg 300w, https:\/\/yongqingbeadsfactory.com\/wp-content\/uploads\/2025\/08\/05-150x150.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n<p>Durante o processamento das esferas de vidro, s\u00e3o aplicados diferentes revestimentos nas suas superf\u00edcies para melhorar a sua resist\u00eancia \u00e0 humidade e as propriedades de liga\u00e7\u00e3o com a tinta, prolongando assim a sua vida \u00fatil e melhorando o seu efeito refletor em condi\u00e7\u00f5es de chuva nocturna. As esferas de vidro com revestimento duplo s\u00e3o normalmente utilizadas na constru\u00e7\u00e3o de linhas brancas ou amarelas nas auto-estradas.<br>A nossa f\u00e1brica pode personalizar e produzir de acordo com diferentes normas nacionais e regionais e requisitos do cliente, incluindo a norma europeia EN1423 e 1424, a norma americana AASHTO M247, a norma brit\u00e2nica BS6088, a norma japonesa JIS R3301 e a norma coreana KS L2521.<\/p>","protected":false},"excerpt":{"rendered":"<p>During the processing of glass beads, different coatings are applied to their surfaces to enhance their moisture resistance and bonding properties with paint, thereby extending their service life and improving their reflective effect under rainy night conditions. Double-coated glass beads are commonly used in the construction of white or yellow lines on highways.Our factory can [&hellip;]<\/p>","protected":false},"author":1,"featured_media":138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products"],"acf":[],"_links":{"self":[{"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/posts\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":1,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/posts\/137\/revisions"}],"predecessor-version":[{"id":139,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/posts\/137\/revisions\/139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/media\/138"}],"wp:attachment":[{"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/media?parent=137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/categories?post=137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yongqingbeadsfactory.com\/pt\/wp-json\/wp\/v2\/tags?post=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}